{"id":2615,"date":"2014-02-21T15:54:15","date_gmt":"2014-02-21T15:54:15","guid":{"rendered":"https:\/\/www.ischia.campania.it\/?page_id=2615"},"modified":"2014-04-02T15:08:40","modified_gmt":"2014-04-02T15:08:40","slug":"la-vita-e-larte-del-pittore-di-ischia-giuseppe-bolivar-patalano","status":"publish","type":"post","link":"https:\/\/www.ischia.campania.it\/index.php\/la-vita-e-larte-del-pittore-di-ischia-giuseppe-bolivar-patalano\/","title":{"rendered":"La vita e l&#8217;arte del pittore di Ischia Giuseppe &#8220;Bolivar&#8221; Patalano"},"content":{"rendered":"<div id=\"itiner-social\" style=\"padding: 5px 0; float:left; width:100%;\"><a href=\"https:\/\/twitter.com\/share\" class=\"twitter-share-button\" data-url=\"http:\/\/www.ischia.campania.it\/index.php\/la-vita-e-larte-del-pittore-di-ischia-giuseppe-bolivar-patalano\/\" data-text=\"ItinerSocial\" data-count=\"horizontal\" data-via=\"ItinerSocial\" style=\"flaot:left;margin: 0 10px\"><\/a><div class=\"fb-like\" data-href=\"http:\/\/www.ischia.campania.it\/index.php\/la-vita-e-larte-del-pittore-di-ischia-giuseppe-bolivar-patalano\/\" data-layout=\"button_count\" data-send=\"false\" data-show-faces=\"false\" data-width=\"90\" style=\"flaot:left;margin: 0 10px\"><\/div><div class=\"g-plusone\" data-annotation=\"inline\" data-href=\"http:\/\/www.ischia.campania.it\/index.php\/la-vita-e-larte-del-pittore-di-ischia-giuseppe-bolivar-patalano\/\" data-size=\"medium\" data-width=\"120\" style=\"flaot:left;margin: 0 10px\"><\/div><\/div><p><strong>Chi ha in mente i panorami, gli scorci, la natura, il<\/strong> <a href=\"https:\/\/www.ischia.campania.it\/index.php\/ischia-un-mare-da-amare\/\">mare di Ischia<\/a> e pensa ingenuamente che la pittura, in un posto del genere, non possa far altro che dedicarsi al vedutismo panoramico, deve &#8220;<em>fare i conti<\/em>&#8221; con l\u2019arte di Giuseppe &#8220;<em>Bolivar<\/em>&#8221; Patalano. Con l\u2019arte, ma ancor di pi\u00f9 con la vita da romanzo di quest\u2019artista &#8220;<em>sui generis<\/em>&#8221; nato a Forio nel 1901 e morto a 80 anni dopo aver vissuto molte vite in una.<\/p>\n<p><strong>Prima, un\u2019adolescenza avventurosa<\/strong>: mozzo, appena quattordicenne, su diverse navi mercantili alla volta di India, Cina, Hong Kong.<\/p>\n<p><strong>Poi emigrante a Providence, Stati Uniti<\/strong>, presso un fratello maggiore, occupato in mille mestieri: cameriere, rappresentante, cassiere in banca e pure giornalista, proprio come il padre Luigi Patalano, ideatore e primo proprietario di quella che poi diverr\u00e0 <a href=\"https:\/\/www.ischia.campania.it\/index.php\/la-colombaia-il-rifugio-dartista-di-luchino-visconti\/\">La Colombaia di Luchino Visconti<\/a>.<\/p>\n<p><strong>Ancora, la Grande Depressione del 1929<\/strong> che come un buco nero inghiottisce cose e persone, compreso la vita di Giuseppe Patalano. Forse un&#8217;amnesia, forse il coinvolgimento pi\u00f9 o meno diretto in un omicidio, fatto sta che agli inizi degli anni \u201830 di lui si perdono le tracce in un ospedale psichiatrico da qualche parte in America.<\/p>\n<p><strong>Infine, dopo 15 anni<\/strong> <strong>(dal 1934 al 1949) di incubi<\/strong>, angosce e sofferenze, il ritorno a casa a seguito del pronunciamento di un giudice che ne ordina l\u2019estradizione dagli Stati Uniti.<\/p>\n<p><strong>Escluso dall\u2019asse ereditario dai fratelli che lo credevano morto;<\/strong> senza lavoro, senza pensione, Giuseppe Patalano prende finalmente in mano la sua vita e comincia a dipingere. Prima di notte per placare l\u2019insonnia febbrile, poi anche di giorno, a casa, per strada, ovunque, fino a quando di lui non si accorge un\u2019artista svizzera, Lel\u00f2 Fiaux, che ne intuisce il talento, lo indirizza al figurativismo e organizza per Giuseppe &#8220;<em>Bolivar<\/em>&#8221; Patalano due personali a Losanna nel 1956 e nel 1961.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div data-carousel-extra='{\"blog_id\":1,\"permalink\":\"https:\\\/\\\/www.ischia.campania.it\\\/index.php\\\/la-vita-e-larte-del-pittore-di-ischia-giuseppe-bolivar-patalano\\\/\"}' id='gallery-1' class='gallery galleryid-2615 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/bolivar-collage.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/bolivar-collage-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/bolivar-collage-150x150.jpg 150w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/bolivar-collage-130x130.jpg 130w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/bolivar-collage-67x67.jpg 67w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/bolivar-collage-40x40.jpg 40w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/bolivar-collage-184x184.jpg 184w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"2614\" data-permalink=\"https:\/\/www.ischia.campania.it\/index.php\/la-vita-e-larte-del-pittore-di-ischia-giuseppe-bolivar-patalano\/bolivar-collage\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/bolivar-collage.jpg\" data-orig-size=\"800,533\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"bolivar-collage\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/bolivar-collage-446x297.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/bolivar-collage.jpg\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar6.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar6-150x150.jpg 150w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar6-130x130.jpg 130w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar6-67x67.jpg 67w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar6-40x40.jpg 40w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar6-184x184.jpg 184w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"2613\" data-permalink=\"https:\/\/www.ischia.campania.it\/bolivar6\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar6.jpg\" data-orig-size=\"627,323\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Bolivar6\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar6-446x229.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar6.jpg\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar5.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar5-150x150.jpg 150w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar5-130x130.jpg 130w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar5-67x67.jpg 67w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar5-40x40.jpg 40w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar5-184x184.jpg 184w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"2612\" data-permalink=\"https:\/\/www.ischia.campania.it\/bolivar5\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar5.jpg\" data-orig-size=\"400,602\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Bolivar5\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar5.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar5.jpg\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar4.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar4-150x150.jpg 150w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar4-130x130.jpg 130w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar4-67x67.jpg 67w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar4-40x40.jpg 40w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar4-184x184.jpg 184w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"2611\" data-permalink=\"https:\/\/www.ischia.campania.it\/bolivar4\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar4.jpg\" data-orig-size=\"408,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Bolivar4\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar4.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar4.jpg\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar3.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar3-150x150.jpg 150w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar3-130x130.jpg 130w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar3-67x67.jpg 67w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar3-40x40.jpg 40w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar3-184x184.jpg 184w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"2610\" data-permalink=\"https:\/\/www.ischia.campania.it\/bolivar3\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar3.jpg\" data-orig-size=\"446,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Bolivar3\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar3.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar3.jpg\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar1.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar1-150x150.jpg 150w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar1-130x130.jpg 130w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar1-67x67.jpg 67w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar1-40x40.jpg 40w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar1-184x184.jpg 184w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-attachment-id=\"2609\" data-permalink=\"https:\/\/www.ischia.campania.it\/bolivar1\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar1.jpg\" data-orig-size=\"293,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Bolivar1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar1.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/Bolivar1.jpg\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p><strong>In quegli anni Forio vive una breve ma intensa stagione artistica<\/strong> di cui sono protagonisti personalit\u00e0 della letteratura come Auden e Moravia, della pittura come Bargheer e Pagliacci, della poesia e della critica letteraria come Libero De Libero. E poi saltuariamente Guttuso, Elsa Morante, Enrico D\u2019Assia e tanti altri, tutti riuniti ai tavolini di un\u2019osteria con un bel pergolato di glicine al centro di Forio: il Bar Internazionale di Maria Senese.<\/p>\n<p><strong>E quell\u2019ambiente cosmopolita che contribuisce all\u2019emancipazione <\/strong>artistica del cinquantenne Patalano che, oltre a frequentare Auden, uno dei massimi interpreti della letteratura e della poesia anglosassone del \u2018900, trova anche l\u2019amore di Maria Maddalena, una conterranea in grado di scrutarne l\u2019anima e lenirne la sofferenza psichica accumulata in quasi vent\u2019anni di ospedale psichiatrico.<\/p>\n<p><strong>\u00c8 la svolta<\/strong>. Si racconta che a Lugano, tanto era lo stupore per quei ritratti &#8220;<em>fra il diabolico e l\u2019estatico inafferrabile<\/em>&#8221; (cit.), la gente facesse la fila al cavalletto di &#8220;<em>Bolivar<\/em>&#8221; come alla porta dello psicanalista.<\/p>\n<p><strong>Negli anni successivi, Giuseppe Patalano <\/strong>\u00e8 stato paragonato a Rembrandt, Cezanne e pure a Van Gogh. Astrattista, impressionista, espressionista, le definizioni che lo hanno riguardato, alle quali per\u00f2 l\u2019uomo ha sempre opposto una semplice constatazione, figlia della familiarit\u00e0 con le antiche maestranze dell&#8217;isola d&#8217;Ischia: &#8220;<em>io sono un muratore<\/em>&#8220;.<\/p>\n<p><strong>Giuseppe Patalano \u00e8 morto nel 1981<\/strong>, lasciando in eredit\u00e0 una gran quantit\u00e0 di opere e, soprattutto, la sua autobiografia \u201cBolivar\u201d scritta e pubblicata in inglese nel 1977, quattro anni prima della sua scomparsa, su incoraggiamento dell\u2019amico poeta Auden.<\/p>\n<p><strong>A seguire alcune delle parole pi\u00f9 belle mai spese dalla critica su Giuseppe &#8220;Bolivar&#8221; Patalano<\/strong>. Estratti delle recensioni contenute nel bel libro &#8220;Artisti dell&#8217;isola d&#8217;Ischia&#8221; a cura di Massimo Ielasi (Societ\u00e0 Editrice Napoletana,1982)<\/p>\n<blockquote><p><em>&#8220;Un volto in apparenza ti sorride; poi, fissandolo, quel sorriso si traforma in un ghigno, si dilata e ti lascia sospeso a mezzo fra il diabolico e l\u2019estatico inafferrabile<\/em>\u201d. (Ettore Settanni)<\/p>\n<p>\u201c<em>La sua \u00e8 pittura dal di dentro<\/em>. [&#8230;] <em>Le sue facce sono solchi nella terra<\/em>. [&#8230;] <em>I suoi ritratti sono allucinanti, crudeli, grotteschi, brutali (&#8230;) \u00e8 un mediterraneo ingenuo, senza retorica, nato dalla sua scuola: quella di non averne frequentata nessuna e di avere fondato la sua<\/em>\u201d. (Manlio Miserocchi)<\/p>\n<p>\u201c<em>T\u2019accosti ed ogni dipinto ti scruta e t\u2019arresta con gli occhi brucianti, fondi di nero<\/em>, (&#8230;) <em>solo a dipingere ancora con quel suo modo divisionista d\u2019espressionisno dolente<\/em>\u201d. (Ercole Camurani)<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Chi ha in mente i panorami, gli scorci, la natura, il mare di Ischia e pensa ingenuamente che la pittura, in un posto del genere, non possa far altro che dedicarsi al vedutismo panoramico, deve &#8220;fare i conti&#8221; con l\u2019arte di Giuseppe &#8220;Bolivar&#8221; Patalano. Con l\u2019arte, ma ancor di pi\u00f9 con la vita da romanzo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"spay_email":""},"categories":[22,1],"tags":[],"jetpack_featured_media_url":"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/02\/bolivar-collage.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3yuov-Gb","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/posts\/2615"}],"collection":[{"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/comments?post=2615"}],"version-history":[{"count":26,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/posts\/2615\/revisions"}],"predecessor-version":[{"id":3083,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/posts\/2615\/revisions\/3083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/media\/2614"}],"wp:attachment":[{"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/media?parent=2615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/categories?post=2615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/tags?post=2615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}