{"id":5345,"date":"2015-01-22T13:13:50","date_gmt":"2015-01-22T12:13:50","guid":{"rendered":"https:\/\/www.ischia.campania.it\/?p=5345"},"modified":"2015-01-22T13:13:50","modified_gmt":"2015-01-22T12:13:50","slug":"ischia-scopri-lisola-in-8-tappe","status":"publish","type":"post","link":"https:\/\/www.ischia.campania.it\/index.php\/ischia-scopri-lisola-in-8-tappe\/","title":{"rendered":"Ischia: scopri l&#8217;isola in 8 tappe"},"content":{"rendered":"<div id=\"itiner-social\" style=\"padding: 5px 0; float:left; width:100%;\"><a href=\"https:\/\/twitter.com\/share\" class=\"twitter-share-button\" data-url=\"http:\/\/www.ischia.campania.it\/index.php\/ischia-scopri-lisola-in-8-tappe\/\" data-text=\"ItinerSocial\" data-count=\"horizontal\" data-via=\"ItinerSocial\" style=\"flaot:left;margin: 0 10px\"><\/a><div class=\"fb-like\" data-href=\"http:\/\/www.ischia.campania.it\/index.php\/ischia-scopri-lisola-in-8-tappe\/\" data-layout=\"button_count\" data-send=\"false\" data-show-faces=\"false\" data-width=\"90\" style=\"flaot:left;margin: 0 10px\"><\/div><div class=\"g-plusone\" data-annotation=\"inline\" data-href=\"http:\/\/www.ischia.campania.it\/index.php\/ischia-scopri-lisola-in-8-tappe\/\" data-size=\"medium\" data-width=\"120\" style=\"flaot:left;margin: 0 10px\"><\/div><\/div><p><strong>270 \u00e8 il nome della (ex) Strada statale che collega i sei comuni dell&#8217;isola<\/strong>. 8, invece, sono le tappe che abbiamo scelto per voi lungo il tragitto. Otto posti in cui fermarsi per scattare\u00a0 foto, godere del panorama e familiarizzare con l&#8217;isola pi\u00f9 bella del Golfo di Napoli.<\/p>\n<p><strong>1 &#8211; Belvedere del Castiglione<br \/>\n<a href=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_9600.jpg\"><img data-attachment-id=\"5347\" data-permalink=\"https:\/\/www.ischia.campania.it\/index.php\/ischia-scopri-lisola-in-8-tappe\/img_9600\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_9600.jpg\" data-orig-size=\"800,533\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_9600\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_9600-446x297.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_9600.jpg\" loading=\"lazy\" class=\"alignnone size-full wp-image-5347\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_9600.jpg\" alt=\"IMG_9600\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_9600.jpg 800w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_9600-446x297.jpg 446w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_9600-140x94.jpg 140w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><br \/>\nPartendo dal porto di Ischia, il belvedere del Castiglione \u00e8 la prima tappa<\/strong> di questo tour alla scoperta dell&#8217;isola d&#8217;Ischia. In realt\u00e0, varrebbe la pena fermarsi anche un po&#8217; prima, all&#8217;altezza del <a href=\"https:\/\/www.ischia.campania.it\/index.php\/il-borgo-di-santalessandro\/\" target=\"_blank\">borgo di Sant&#8217;Alessandro<\/a> (c&#8217;\u00e8 un parcheggio proprio di fronte il borgo in cui fermare l&#8217;auto o lo scooter). A ogni modo, la vista dal belvedere del Castiglione, a poche decine di metri dall&#8217;omonimo parco termale, \u00e8 l&#8217;ideale per un primo approccio con l&#8217;aria, le vedute e i colori di Ischia.<\/p>\n<p><strong>2 &#8211; Belvedere di Montevico<\/strong><br \/>\n<a href=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_7948.jpg\"><img data-attachment-id=\"5348\" data-permalink=\"https:\/\/www.ischia.campania.it\/index.php\/ischia-scopri-lisola-in-8-tappe\/img_7948\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_7948.jpg\" data-orig-size=\"800,533\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7948\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_7948-446x297.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_7948.jpg\" loading=\"lazy\" class=\"alignnone size-full wp-image-5348\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_7948.jpg\" alt=\"IMG_7948\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_7948.jpg 800w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_7948-446x297.jpg 446w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_7948-140x94.jpg 140w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><br \/>\n<strong>Se il corso Angelo Rizzoli a Lacco Ameno \u00e8 aperto, <\/strong>la prima cosa da fare \u00e8 fermarsi davanti al &#8220;Fungo&#8221;, una delle cartoline pi\u00f9 celebri dell&#8217;isola d&#8217;Ischia (vedi foto di copertina). Il tempo di un &#8220;<em>selfie<\/em>&#8221; con lo sfondo di questo mega blocco di tufo a pochi metri dalla riva e si raggiunge velocemente il belvedere di Montevico, la collina che da un lato cinge il porto e le spiagge del centro;\u00a0 dall&#8217;altro, la splendida baia di San Montano. Il panorama abbraccia per intero la litoranea che congiunge <a href=\"https:\/\/www.ischia.campania.it\/index.php\/alla-scoperta-di-lacco-ameno\/\" target=\"_blank\">Lacco Ameno<\/a> e Casamicciola, con i porti, le luci e le attivit\u00e0 dei due comuni simbolo della rinascita turistica dell&#8217;isola d&#8217;Ischia. Molto bella la vista sul far della sera, ancora di pi\u00f9 durante la festa di Santa Restituta (patrona di Lacco Ameno) nel mese di maggio. Da quass\u00f9, le luminarie, le luci e i fuochi d&#8217;artificio regalano emozioni e&#8230; scatti davvero unici.<\/p>\n<p><strong>3 &#8211; Belvedere di Zaro<br \/>\n<a href=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_3497.jpg\"><img data-attachment-id=\"5349\" data-permalink=\"https:\/\/www.ischia.campania.it\/index.php\/ischia-scopri-lisola-in-8-tappe\/img_3497\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_3497.jpg\" data-orig-size=\"800,533\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_3497\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_3497-446x297.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_3497.jpg\" loading=\"lazy\" class=\"alignnone size-full wp-image-5349\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_3497.jpg\" alt=\"IMG_3497\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_3497.jpg 800w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_3497-446x297.jpg 446w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/IMG_3497-140x94.jpg 140w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>Proseguendo per Forio \u00e8 d&#8217;obbligo un salto al belvedere Josemar\u00eda Escriv\u00e1 de Balaguer<\/strong>, sulla strada che porta al <a href=\"https:\/\/www.ischia.campania.it\/index.php\/forio-a-spasso-per-il-bosco-di-zaro\/\" target=\"_blank\">bosco di Zaro<\/a>. D&#8217;estate, la vista dei ristoranti sul mare, gli ombrelloni, i\u00a0 turisti in acqua, \u00e8 l&#8217;istantanea perfetta di una localit\u00e0 balneare.\u00a0 Nel resto dell&#8217;anno, ma anche di primo mattino, le emozioni cambiano: ora vivaci, ora pi\u00f9 contemplative a seconda della luminosit\u00e0 e delle condizioni meteo marine.<\/p>\n<p><strong>4 &#8211; Borgo di Sant&#8217;Angelo<\/strong><br \/>\n<a href=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/09\/IMG_1384.jpg\"><img data-attachment-id=\"4545\" data-permalink=\"https:\/\/www.ischia.campania.it\/index.php\/ischia-scopri-lisola-in-8-tappe\/img_1384\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/09\/IMG_1384.jpg\" data-orig-size=\"800,533\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"IMG_1384\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/09\/IMG_1384-446x297.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/09\/IMG_1384.jpg\" loading=\"lazy\" class=\"alignnone size-full wp-image-4545\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/09\/IMG_1384.jpg\" alt=\"IMG_1384\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/09\/IMG_1384.jpg 800w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/09\/IMG_1384-446x297.jpg 446w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/09\/IMG_1384-140x94.jpg 140w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><br \/>\n<strong> Impensabile non fermarsi a Sant&#8217;Angelo<\/strong>,\u00a0anche solo il tempo di un caff\u00e8, un aperitivo, un dolce in piazzetta. Un antico <a href=\"https:\/\/www.ischia.campania.it\/index.php\/i-borghi-marinari-dellisola-dischia\/\" target=\"_blank\">borgo di pescatori<\/a> che negli anni ha saputo trasformarsi nella pi\u00f9 esclusiva localit\u00e0 turistica dell&#8217;isola, senza smarrire, anzi valorizzando, la sua impronta marinara. Una delle testimonianze pi\u00f9 significative di quel modo di costruire &#8220;<em>sui generis<\/em>&#8221;\u00a0 che \u00e8 l&#8217;architettura mediterranea.<\/p>\n<p><strong>5 &#8211; Belvedere di Serrara<br \/>\n<a href=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/01\/ANT_0147.jpg\"><img data-attachment-id=\"2426\" data-permalink=\"https:\/\/www.ischia.campania.it\/index.php\/ischia-cosa-vedere\/ant_0147\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/01\/ANT_0147.jpg\" data-orig-size=\"750,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"ANT_0147\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/01\/ANT_0147-446x297.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/01\/ANT_0147.jpg\" loading=\"lazy\" class=\"alignnone size-full wp-image-2426\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/01\/ANT_0147.jpg\" alt=\"ANT_0147\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/01\/ANT_0147.jpg 750w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/01\/ANT_0147-446x297.jpg 446w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/01\/ANT_0147-140x94.jpg 140w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a><br \/>\nLa quinta tappa \u00e8 il belvedere di <a href=\"https:\/\/www.ischia.campania.it\/index.php\/alla-scoperta-di-serrara-fontana\/\" target=\"_blank\">Serrara Fontana<\/a><\/strong>, probabilmente il pi\u00f9 famoso di quelli sinora descritti. Magia purissima, con la &#8220;Torre&#8221; (l&#8217;isolotto tufaceo davanti la piazzetta di Sant&#8217;Angelo) in primo piano e la vista panoramica dell&#8217;intero versante meridionale dell&#8217;isola. Sullo sfondo, sorniona, Capri.<\/p>\n<p><strong>6 &#8211; La piazza di Buonopane<\/strong><br \/>\n<a href=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/04\/100_3433.jpg\"><img data-attachment-id=\"3491\" data-permalink=\"https:\/\/www.ischia.campania.it\/index.php\/ischia-scopri-lisola-in-8-tappe\/100_3433\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/04\/100_3433.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"100_3433\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/04\/100_3433-446x334.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/04\/100_3433.jpg\" loading=\"lazy\" class=\"alignnone size-full wp-image-3491\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/04\/100_3433.jpg\" alt=\"100_3433\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/04\/100_3433.jpg 800w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/04\/100_3433-446x334.jpg 446w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><br \/>\n<strong>A Buonopane (frazione del comune di Barano)<\/strong> <strong>non ci si ferma per il panorama<\/strong>, anche se, poco oltre, sulla strada che porta a Candiano, non mancano certo scorci e vedute mozzafiato. A Buonopane ci si ferma per fare il &#8220;<em>pieno<\/em>&#8221; di tradizioni e osservare i murales che raffigurano i diversi momenti della<a href=\"https:\/\/www.ischia.campania.it\/index.php\/la-ndrezzata-di-buonopane\/\" target=\"_blank\"> &#8216;ndrezzata<\/a>, la celebre danza di origine greca che proprio qui, in questa amena contrada, viene tuttora tramandata di padre in figlio.<\/p>\n<p><strong>7 &#8211; Belvedere dei Maronti<\/strong><br \/>\n<a href=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/05\/IMG_2938.jpg\"><img data-attachment-id=\"3766\" data-permalink=\"https:\/\/www.ischia.campania.it\/index.php\/ischia-scopri-lisola-in-8-tappe\/img_2938\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/05\/IMG_2938.jpg\" data-orig-size=\"800,533\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"IMG_2938\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/05\/IMG_2938-446x297.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/05\/IMG_2938.jpg\" loading=\"lazy\" class=\"alignnone size-full wp-image-3766\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/05\/IMG_2938.jpg\" alt=\"IMG_2938\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/05\/IMG_2938.jpg 800w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/05\/IMG_2938-446x297.jpg 446w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2014\/05\/IMG_2938-140x94.jpg 140w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><br \/>\n<strong>Dopo Buonopane \u00e8 la volta dei Maronti, una delle <a href=\"https:\/\/www.ischia.campania.it\/index.php\/la-spiagge-piu-belle-dellisola-dischia\/\" target=\"_blank\">spiagge pi\u00f9 belle dell&#8217;isola d&#8217;Ischia<\/a><\/strong>. Meglio, \u00e8 la volta del belvedere dei Maronti, poco dopo l&#8217;inizio dei tornanti che portano all&#8217;arenile. Il blu del mare e la sinuosit\u00e0 delle curve descrivono meglio di tante parole non solo la &#8220;<em>bellezza<\/em>&#8220;, ma anche la &#8220;<em>fatica<\/em>&#8221; necessaria a domare la difficile natura ischitana (fino agli anni &#8217;60 del secolo scorso la strada non c&#8217;era).<\/p>\n<p><strong>8 &#8211; Il Castello Aragonese<\/strong><br \/>\n<a href=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2013\/10\/castello.jpg\"><img data-attachment-id=\"1961\" data-permalink=\"https:\/\/www.ischia.campania.it\/index.php\/ischia-scopri-lisola-in-8-tappe\/castello\/\" data-orig-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2013\/10\/castello.jpg\" data-orig-size=\"800,533\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"castello\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2013\/10\/castello-446x297.jpg\" data-large-file=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2013\/10\/castello.jpg\" loading=\"lazy\" class=\"alignnone size-full wp-image-1961\" src=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2013\/10\/castello.jpg\" alt=\"castello\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2013\/10\/castello.jpg 800w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2013\/10\/castello-446x297.jpg 446w, https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2013\/10\/castello-140x94.jpg 140w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><br \/>\n<strong>Il tour non poteva che terminare con la fortezza di &#8220;<em>Alfonso Il Magnanimo<\/em>&#8220;<\/strong>. Solo, anzich\u00e8 dirigervi verso Ischia Ponte,\u00a0 seguite le indicazioni per Cartaromana (svoltando a destra all&#8217;altezza dell&#8217;<a href=\"https:\/\/www.ischia.campania.it\/index.php\/lacquedotto-dei-pilastri\/\" target=\"_blank\">Acquedotto dei Pilastri<\/a>) uno dei quartieri resdienziali pi\u00f9 &#8220;<em>in<\/em>&#8221; del comune di Ischia. Nell&#8217;ultimo tratto di strada, quello che porta alla Torre di Guevara, il Castello Aragonese \u00e8 cos\u00ec vicino che pare di toccarlo. L&#8217;ideale per un&#8217;ultimo scatto, prima del rientro e&#8230; la prossima avventura!<\/p>\n<p><strong>Ti potrebbe interessare anche<\/strong>:<br \/>\n<a href=\"https:\/\/www.ischia.campania.it\/index.php\/ischia-toccata-e-fuga-cosa-vedere-in-un-giorno-a-ischia\/\" target=\"_blank\">Ischia, toccata e fuga. Cosa vedere in un giorno a Ischia<\/a><\/p>\n<p><em><strong>Ischia Vi aspetta!<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>270 \u00e8 il nome della (ex) Strada statale che collega i sei comuni dell&#8217;isola. 8, invece, sono le tappe che abbiamo scelto per voi lungo il tragitto. Otto posti in cui fermarsi per scattare\u00a0 foto, godere del panorama e familiarizzare con l&#8217;isola pi\u00f9 bella del Golfo di Napoli. 1 &#8211; Belvedere del Castiglione Partendo dal [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5358,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"spay_email":""},"categories":[21,1],"tags":[],"jetpack_featured_media_url":"https:\/\/www.ischia.campania.it\/wp-content\/uploads\/2015\/01\/copertina-panorami-ischia.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3yuov-1od","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/posts\/5345"}],"collection":[{"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/comments?post=5345"}],"version-history":[{"count":7,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/posts\/5345\/revisions"}],"predecessor-version":[{"id":5356,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/posts\/5345\/revisions\/5356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/media\/5358"}],"wp:attachment":[{"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/media?parent=5345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/categories?post=5345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ischia.campania.it\/index.php\/wp-json\/wp\/v2\/tags?post=5345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}